{"id":1867,"date":"2015-08-31T16:51:18","date_gmt":"2015-08-31T19:51:18","guid":{"rendered":"http:\/\/www2.faac.unesp.br\/blog\/obsmidia\/?p=1867"},"modified":"2015-09-17T17:02:23","modified_gmt":"2015-09-17T20:02:23","slug":"o-silencio-multissecular-da-cultura-brasileira","status":"publish","type":"post","link":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/2015\/08\/31\/o-silencio-multissecular-da-cultura-brasileira\/","title":{"rendered":"O sil\u00eancio multissecular da cultura brasileira"},"content":{"rendered":"<p><span style=\"color: #000000\"><strong>\u2016 \u2016 \u2016 Murilo C. Soares\u00a0\u2016 \u2016 \u2016 <\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><span style=\"color: #000000\"><em>S\u00f3 \u00e9 poss\u00edvel compreender a cultura do sil\u00eancio se a tomarmos como uma totalidade que \u00e9, ela pr\u00f3pria, parte de um todo maior.\u00a0 [&#8230;]\u00a0 A sociedade dependente \u00e9 por defini\u00e7\u00e3o, uma sociedade silenciosa.<\/em><\/span><\/p>\n<p style=\"text-align: right\"><span style=\"color: #000000\"><em>Paulo Freire<\/em><\/span><\/p>\n<p><span style=\"color: #000000\"><strong>\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #000000\"><strong>\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #000000\"><span style=\"color: #0000ff\">\u201c<\/span><a style=\"color: #000000\" href=\"http:\/\/www.editora.unb.br\/lstDetalhaProduto.aspx?pid=760\" target=\"_blank\"><span style=\"color: #0000ff\">Cultura do sil\u00eancio e democracia no Brasil \u2013 ensaios em defesa da liberdade de express\u00e3o (1980-2015)\u201d<\/span>,<\/a> de Ven\u00edcio Artur de Lima, lan\u00e7ado este ano, \u00e9 uma obra panor\u00e2mica, cobrindo 35 anos de produ\u00e7\u00e3o intelectual de um autor que contribui destacadamente para o pensamento da comunica\u00e7\u00e3o e da pol\u00edtica no Brasil.\u00a0\u00a0 Pensador e pesquisador, com uma \u00a0trajet\u00f3ria investigativa original, Ven\u00edcio oferece nesse livro uma reuni\u00e3o de suas reflex\u00f5es, em campos nos quais se tornou refer\u00eancia, influenciando colegas e orientandos e inspirando pesquisas.<\/span><\/p>\n<p><span style=\"color: #000000\">A obra foi lan\u00e7ada pela Editora da Universidade de Bras\u00edlia, onde o autor foi professor titular de Ci\u00eancia Pol\u00edtica e Comunica\u00e7\u00e3o, ap\u00f3s cursar o mestrado e doutorado na University of Illinois.\u00a0 Ven\u00edcio \u00e9 tamb\u00e9m p\u00f3s-doutor pela University of Illinois e pela University of Miami-Ohio.\u00a0 Foi professor visitante nas universidades de Illinois e Miami-Ohio, nos Estados Unidos e na La Habana, Cuba. \u00a0Coordenou a p\u00f3s-gradua\u00e7\u00e3o da Universidade Estadual do Rio Grande do Sul e foi pesquisador visitante da UFMG.\u00a0 Atualmente, \u00e9 colaborador do Observat\u00f3rio da Imprensa, do portal Carta Maior, da revista Teoria e Debate e pesquisador do Centro de Estudos Republicanos da UFMG.<\/span><\/p>\n<p><span style=\"color: #000000\">O livro traz vinte ensaios organizados em torno de cinco eixos, como escreve o pr\u00f3prio Lima: \u201cdois autores \u2013 Paulo Freire e Stuart Hall \u2013 e tr\u00eas temas \u2013 pol\u00edticas p\u00fablicas de comunica\u00e7\u00e3o, m\u00eddia e pol\u00edtica e liberdade de express\u00e3o.\u201d\u00a0 O t\u00edtulo \u00e9 uma refer\u00eancia a autores como o padre Antonio Vieira, que, no serm\u00e3o da Visita\u00e7\u00e3o de Nossa Senhora, de 1640, afirmou: \u201cO pior acidente que teve o Brasil em sua enfermidade foi o tolher-se-lhe a fala&#8230;\u201d\u00a0 Lima retoma o tema, com Paulo Freire, autor sobre o qual versou seu doutoramento.\u00a0 Para Lima, <em>cultura do sil\u00eancio<\/em> \u00e9 um conceito\u00a0 freireano, a partir da observa\u00e7\u00e3o do padre Vieira, sobre o Brasil do s\u00e9culo XVII.\u00a0 Segundo Lima, a cultura do sil\u00eancio \u201ccaracteriza a sociedade a que se nega a comunica\u00e7\u00e3o e o di\u00e1logo e, em seu lugar, se lhe oferece \u201ccomunicados\u201d, vale dizer, \u00e9 o ambiente do tolhimento da voz e da aus\u00eancia de comunica\u00e7\u00e3o, da incomunicabilidade\u201d.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000\">Essa no\u00e7\u00e3o cr\u00edtica constitui a categoria central do livro, em torno da qual se integram as an\u00e1lises que formam os eixos da obra.\u00a0 O primeiro desses eixos, das pol\u00edticas de comunica\u00e7\u00e3o, trata da comunica\u00e7\u00e3o na Constituinte de 1987-1988, do interesse privado versus interesse p\u00fablico, dos Conselhos de Comunica\u00e7\u00e3o Social.\u00a0 No segundo eixo, m\u00eddia e pol\u00edtica, o foco recai sobre a liberdade de express\u00e3o, os conceitos de cen\u00e1rios de representa\u00e7\u00e3o da pol\u00edtica e de coronelismo eletr\u00f4nico.\u00a0 O terceiro eixo, da liberdade de express\u00e3o, aborda as diferen\u00e7as entre liberdade de express\u00e3o e liberdade da imprensa, enfoca a m\u00eddia e a justi\u00e7a no Brasil e a censura decorrente da a\u00e7\u00e3o dos oligop\u00f3lios medi\u00e1ticos.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000\">Fruto de trabalhos escritos ao longo de tr\u00eas d\u00e9cadas, por um autor\u00a0 que foi, muitas vezes, testemunha dos acontecimentos e dos assuntos analisados, \u201cCultura do Sil\u00eancio\u201d combina a perspectiva cr\u00edtica com a coes\u00e3o interna, apesar da diversidade dos objetos tratados.\u00a0 Constitui uma obra madura, reflexiva, de um intelectual a caminho de se tornar um cl\u00e1ssico, como salienta o pref\u00e1cio de Juarez Guimar\u00e3es.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000\"><em>Acesse <\/em><span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"http:\/\/www2.faac.unesp.br\/blog\/obsmidia\/files\/Introducao-Venicio-Lima.pdf\" target=\"_blank\"><em>aqui<\/em><\/a><\/span><em> a introdu\u00e7\u00e3o do livro.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000\"><strong>\u00a0<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2016 \u2016 \u2016 Murilo C. Soares\u00a0\u2016 \u2016 \u2016 &nbsp; S\u00f3 \u00e9 poss\u00edvel compreender a cultura do sil\u00eancio se a tomarmos como uma totalidade que \u00e9, ela pr\u00f3pria, parte de um todo maior.\u00a0 [&#8230;]\u00a0 A sociedade dependente \u00e9 por defini\u00e7\u00e3o, uma sociedade silenciosa. Paulo Freire \u00a0 \u00a0 \u201cCultura do sil\u00eancio e democracia no Brasil \u2013 ensaios [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23,22],"tags":[42,51],"_links":{"self":[{"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/posts\/1867"}],"collection":[{"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/comments?post=1867"}],"version-history":[{"count":1,"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/posts\/1867\/revisions"}],"predecessor-version":[{"id":1869,"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/posts\/1867\/revisions\/1869"}],"wp:attachment":[{"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/media?parent=1867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/categories?post=1867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.faac.unesp.br\/blog\/obsmidia\/wp-json\/wp\/v2\/tags?post=1867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}